{"id":6312,"count":3,"description":"","link":"https:\/\/next.eventail.be\/nl\/tag\/afrikaanse-kunst","name":"Afrikaanse kunst","slug":"afrikaanse-kunst","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v20.11 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Afrikaanse kunst &#8226; L&#039;\u00c9ventail<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Afrikaanse kunst\" \/>\n<meta property=\"og:site_name\" content=\"L&#039;\u00c9ventail\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/abonnement.eventail.be\/nl\/tag\/afrikaanse-kunst\",\"url\":\"https:\/\/abonnement.eventail.be\/nl\/tag\/afrikaanse-kunst\",\"name\":\"Afrikaanse kunst &#8226; L&#039;\u00c9ventail\",\"isPartOf\":{\"@id\":\"https:\/\/abonnement.eventail.be\/nl#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/abonnement.eventail.be\/nl\/tag\/afrikaanse-kunst#breadcrumb\"},\"inLanguage\":\"nl-NL\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/abonnement.eventail.be\/nl\/tag\/afrikaanse-kunst#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/abonnement.eventail.be\/nl\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Afrikaanse kunst\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/abonnement.eventail.be\/nl#website\",\"url\":\"https:\/\/abonnement.eventail.be\/nl\",\"name\":\"L&#039;\u00c9ventail\",\"description\":\"Le Magazine de l\u2019art de vivre\",\"publisher\":{\"@id\":\"https:\/\/abonnement.eventail.be\/nl#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/abonnement.eventail.be\/nl?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/abonnement.eventail.be\/nl#organization\",\"name\":\"L'Eventail\",\"url\":\"https:\/\/abonnement.eventail.be\/nl\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\/\/abonnement.eventail.be\/nl#\/schema\/logo\/image\/\",\"url\":\"https:\/\/abonnement.eventail.be\/wp-content\/uploads\/2022\/01\/logo.svg\",\"contentUrl\":\"https:\/\/abonnement.eventail.be\/wp-content\/uploads\/2022\/01\/logo.svg\",\"width\":1,\"height\":1,\"caption\":\"L'Eventail\"},\"image\":{\"@id\":\"https:\/\/abonnement.eventail.be\/nl#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Eventail.Magazine\",\"https:\/\/www.instagram.com\/eventail.be\",\"https:\/\/www.pinterest.com\/leventail\/\"]}]}<\/script>\n<title>Afrikaanse kunst &#8226; L&#039;\u00c9ventail<\/title>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Afrikaanse kunst &#8226; L&#039;\u00c9ventail","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"nl_NL","og_type":"article","og_title":"Afrikaanse kunst","og_site_name":"L&#039;\u00c9ventail","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/abonnement.eventail.be\/nl\/tag\/afrikaanse-kunst","url":"https:\/\/abonnement.eventail.be\/nl\/tag\/afrikaanse-kunst","name":"Afrikaanse kunst &#8226; L&#039;\u00c9ventail","isPartOf":{"@id":"https:\/\/abonnement.eventail.be\/nl#website"},"breadcrumb":{"@id":"https:\/\/abonnement.eventail.be\/nl\/tag\/afrikaanse-kunst#breadcrumb"},"inLanguage":"nl-NL"},{"@type":"BreadcrumbList","@id":"https:\/\/abonnement.eventail.be\/nl\/tag\/afrikaanse-kunst#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/abonnement.eventail.be\/nl"},{"@type":"ListItem","position":2,"name":"Afrikaanse kunst"}]},{"@type":"WebSite","@id":"https:\/\/abonnement.eventail.be\/nl#website","url":"https:\/\/abonnement.eventail.be\/nl","name":"L&#039;\u00c9ventail","description":"Le Magazine de l\u2019art de vivre","publisher":{"@id":"https:\/\/abonnement.eventail.be\/nl#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/abonnement.eventail.be\/nl?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/abonnement.eventail.be\/nl#organization","name":"L'Eventail","url":"https:\/\/abonnement.eventail.be\/nl","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/abonnement.eventail.be\/nl#\/schema\/logo\/image\/","url":"https:\/\/abonnement.eventail.be\/wp-content\/uploads\/2022\/01\/logo.svg","contentUrl":"https:\/\/abonnement.eventail.be\/wp-content\/uploads\/2022\/01\/logo.svg","width":1,"height":1,"caption":"L'Eventail"},"image":{"@id":"https:\/\/abonnement.eventail.be\/nl#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Eventail.Magazine","https:\/\/www.instagram.com\/eventail.be","https:\/\/www.pinterest.com\/leventail\/"]}]}},"_links":{"self":[{"href":"https:\/\/next.eventail.be\/nl\/wp-json\/wp\/v2\/tags\/6312","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/next.eventail.be\/nl\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/next.eventail.be\/nl\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/next.eventail.be\/nl\/wp-json\/wp\/v2\/posts?tags=6312"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}